<input type="hidden" id="_wpnonce" name="_wpnonce" value="1fbfd39e73" /><input type="hidden" name="_wp_http_referer" value="/blog/wp-json/wp/v2/posts/16860" /><input type="hidden" id="_wpnonce" name="_wpnonce" value="1fbfd39e73" /><input type="hidden" name="_wp_http_referer" value="/blog/wp-json/wp/v2/posts/16860" />{"id":16860,"date":"2017-12-23T22:00:23","date_gmt":"2017-12-23T11:00:23","guid":{"rendered":"https:\/\/www.businesslegions.com\/blog\/2017\/12\/23\/java-programming-for-mobile-developers-for-36-3\/"},"modified":"2017-12-23T22:00:23","modified_gmt":"2017-12-23T11:00:23","slug":"java-programming-for-mobile-developers-for-36-3","status":"publish","type":"post","link":"https:\/\/www.businesslegions.com\/blog\/2017\/12\/23\/java-programming-for-mobile-developers-for-36-3\/","title":{"rendered":"Java Programming for Mobile Developers for $36"},"content":{"rendered":"<!--CusAds0--><div class=\"aligncenter\"><a href=\"https:\/\/stacksocial.com\/sales\/java-programming-for-mobile-developers-2?utm_campaign=feed&#038;utm_medium=RSS&#038;utm_source=www?ref=businesslegions\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/cdn.businesslegions.com\/blog\/wp-content\/uploads\/2016\/03\/buynow-blue.png?strip=all&w=960\" alt=\"\" \/><\/a><\/div>\n<div class=\"aligncenter\"><a href=\"https:\/\/stacksocial.com\/sales\/java-programming-for-mobile-developers-2?utm_campaign=feed&#038;utm_medium=RSS&#038;utm_source=www?ref=businesslegions\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/cdn.businesslegions.com\/blog\/wp-content\/uploads\/2016\/03\/buynow-blue.png?strip=all&w=960\" alt=\"\" \/><\/a><\/div>\n<div class=\"lt-box\" style=\"border:1px solid #1d6a9e\"><div class=\"lt-box-title\" style=\"background-color:#2485C6;border-top:1px solid #a7cee8;text-shadow:1px 1px 0 #0b283b\">DO YOU LIKE WHAT YOU'VE READ?<\/div><div class=\"lt-box-content\">Join our subscription list and receive our content right in your mailbox. If you like to receive some Great deals our Freebies then subscribe now!\r\n\r\n<p><div class=\"tnp tnp-subscription \">\n<form method=\"post\" action=\"https:\/\/www.businesslegions.com\/blog\/wp-admin\/admin-ajax.php?action=tnp&amp;na=s\">\n<input type=\"hidden\" name=\"nlang\" value=\"\">\n<div class=\"tnp-field tnp-field-firstname\"><label for=\"tnp-1\">Name<\/label>\n<input class=\"tnp-name\" type=\"text\" name=\"nn\" id=\"tnp-1\" value=\"\" placeholder=\"\"><\/div>\n<div class=\"tnp-field tnp-field-email\"><label for=\"tnp-2\">Email<\/label>\n<input class=\"tnp-email\" type=\"email\" name=\"ne\" id=\"tnp-2\" value=\"\" placeholder=\"\" required><\/div>\n<div class=\"tnp-field tnp-field-button\" style=\"text-align: left\"><input class=\"tnp-submit\" type=\"submit\" value=\"Subscribe\" style=\"\">\n<\/div>\n<\/form>\n<\/div>\n<\/p>\r\n\r\n<\/div><\/div><!--CusAds0-->\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>DO YOU LIKE WHAT YOU&#8217;VE READ?Join our subscription list and receive our content right in your mailbox. If you like to receive some Great deals our Freebies then subscribe now! Name Email<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,2043,2045,2044,2046],"tags":[3133,2009,916,648,1133,1784,652,3049,94],"class_list":["post-16860","post","type-post","status-publish","format-standard","hentry","category-business","category-deals","category-design","category-entrepreneur","category-website","tag-business","tag-deals","tag-design","tag-developers","tag-entrepreneur","tag-java","tag-mobile","tag-programming","tag-website"],"_links":{"self":[{"href":"https:\/\/www.businesslegions.com\/blog\/wp-json\/wp\/v2\/posts\/16860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.businesslegions.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.businesslegions.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.businesslegions.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.businesslegions.com\/blog\/wp-json\/wp\/v2\/comments?post=16860"}],"version-history":[{"count":0,"href":"https:\/\/www.businesslegions.com\/blog\/wp-json\/wp\/v2\/posts\/16860\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.businesslegions.com\/blog\/wp-json\/wp\/v2\/media?parent=16860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.businesslegions.com\/blog\/wp-json\/wp\/v2\/categories?post=16860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.businesslegions.com\/blog\/wp-json\/wp\/v2\/tags?post=16860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}